{"id":23417,"date":"2022-10-06T15:01:07","date_gmt":"2022-10-06T13:01:07","guid":{"rendered":"https:\/\/www.atmos.eu\/udalost\/infotherma-ostrava-2023\/"},"modified":"2024-06-11T08:37:40","modified_gmt":"2024-06-11T06:37:40","slug":"infotherma-ostrava-2023","status":"publish","type":"event","link":"https:\/\/www.atmos.eu\/fr\/\u00e9v\u00e9nement\/infotherma-ostrava-2023\/","title":{"rendered":"Infotherma &#8211; Ostrava 2023"},"content":{"rendered":"<div>\n<p style=\"text-align: left;\"><strong><span style=\"font-family: arial, helvetica, sans-serif;\">La 28e \u00e9dition du salon international INFOTERMA aura lieu du 23 au 26 janvier 2023, tous les jours de 9h00 \u00e0 18h00, le jeudi de 9h00 \u00e0 16h00 au Parc des Expositions d&rsquo;Ostrava.<\/span><\/strong><\/p>\n<p style=\"text-align: left;\"><strong><span style=\"font-family: arial, helvetica, sans-serif;\">Si vous ne t\u00e9l\u00e9chargez pas de billet gratuit, c&rsquo;est le prix d&rsquo;entr\u00e9e au salon INFOTERMA 2023.<\/span><\/strong><br \/>\n<strong><span style=\"font-family: arial, helvetica, sans-serif;\">100 CZK (TVA incluse).<\/span><\/strong><br \/>\n<strong><span style=\"font-family: arial, helvetica, sans-serif;\">Si vous ne t\u00e9l\u00e9chargez pas de billet gratuit, le prix d&rsquo;entr\u00e9e au salon INFOTERMA 2023 est r\u00e9duit<\/span><\/strong><br \/>\n<strong><span style=\"font-family: arial, helvetica, sans-serif;\">50 CZK (TVA incluse).<\/span><\/strong><\/p>\n<p style=\"text-align: left;\">\n<p style=\"text-align: left;\"><strong><span style=\"font-family: arial, helvetica, sans-serif;\">B\u00e9n\u00e9ficient d&rsquo;une entr\u00e9e \u00e0 tarif r\u00e9duit sur pr\u00e9sentation du document appropri\u00e9\u00a0:<\/span><\/strong><\/p>\n<p style=\"text-align: left;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Porte-cartes TP, ZTP, ZTP\/P, ZTP\/P \u2013 guide gratuit.<\/span><\/p>\n<p style=\"text-align: left;\"><span style=\"font-family: arial, helvetica, sans-serif;\">L&rsquo;entr\u00e9e est gratuite pour les \u00e9coles professionnelles sur accord pr\u00e9alable avec les organisateurs de l&rsquo;exposition (envoyer la liste des \u00e9l\u00e8ves et de l&rsquo;encadrement p\u00e9dagogique avec le nom de l&rsquo;\u00e9cole \u00e0 l&rsquo;adresse e-mail &#8211; bujakova@inforpres.cz).<\/span><\/p>\n<p style=\"text-align: left;\"><strong><span style=\"font-family: arial, helvetica, sans-serif;\">Il r\u00e9sulte du r\u00e8glement technique et de s\u00e9curit\u00e9 qu&rsquo;il est interdit de p\u00e9n\u00e9trer dans les locaux d&rsquo;exposition avec des poussettes.<\/span><\/strong><br \/>\n<span style=\"font-family: arial, helvetica, sans-serif;\">Les poussettes peuvent \u00eatre entrepos\u00e9es gratuitement au vestiaire \u00e0 l&rsquo;entr\u00e9e.<\/span><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La 28e \u00e9dition du salon international INFOTERMA aura lieu du 23 au 26 janvier 2023, tous les jours de 9h00 \u00e0 18h00, le jeudi de 9h00 \u00e0 16h00 au Parc des Expositions d&rsquo;Ostrava. Si vous ne t\u00e9l\u00e9chargez pas de billet gratuit, c&rsquo;est le prix d&rsquo;entr\u00e9e au salon INFOTERMA 2023. 100 CZK (TVA incluse). Si vous&#8230;<\/p>\n","protected":false},"featured_media":22624,"menu_order":1,"template":"","class_list":["post-23417","event","type-event","status-publish","has-post-thumbnail","hentry","event-category-2023-fr","tag_event-republique-tcheque"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Infotherma - Ostrava 2023 - ATMOS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.atmos.eu\/fr\/\u00e9v\u00e9nement\/infotherma-ostrava-2023\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Infotherma - Ostrava 2023 - ATMOS\" \/>\n<meta property=\"og:description\" content=\"La 28e \u00e9dition du salon international INFOTERMA aura lieu du 23 au 26 janvier 2023, tous les jours de 9h00 \u00e0 18h00, le jeudi de 9h00 \u00e0 16h00 au Parc des Expositions d&rsquo;Ostrava. Si vous ne t\u00e9l\u00e9chargez pas de billet gratuit, c&rsquo;est le prix d&rsquo;entr\u00e9e au salon INFOTERMA 2023. 100 CZK (TVA incluse). Si vous...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.atmos.eu\/fr\/\u00e9v\u00e9nement\/infotherma-ostrava-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"ATMOS\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-11T06:37:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.atmos.eu\/wp-content\/uploads\/2022\/10\/Infotherma-2023-logo-300x156-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"156\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Infotherma - Ostrava 2023 - ATMOS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.atmos.eu\/fr\/\u00e9v\u00e9nement\/infotherma-ostrava-2023\/","og_locale":"fr_FR","og_type":"article","og_title":"Infotherma - Ostrava 2023 - ATMOS","og_description":"La 28e \u00e9dition du salon international INFOTERMA aura lieu du 23 au 26 janvier 2023, tous les jours de 9h00 \u00e0 18h00, le jeudi de 9h00 \u00e0 16h00 au Parc des Expositions d&rsquo;Ostrava. Si vous ne t\u00e9l\u00e9chargez pas de billet gratuit, c&rsquo;est le prix d&rsquo;entr\u00e9e au salon INFOTERMA 2023. 100 CZK (TVA incluse). Si vous...","og_url":"https:\/\/www.atmos.eu\/fr\/\u00e9v\u00e9nement\/infotherma-ostrava-2023\/","og_site_name":"ATMOS","article_modified_time":"2024-06-11T06:37:40+00:00","og_image":[{"width":300,"height":156,"url":"https:\/\/www.atmos.eu\/wp-content\/uploads\/2022\/10\/Infotherma-2023-logo-300x156-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.atmos.eu\/fr\/\u00e9v\u00e9nement\/infotherma-ostrava-2023\/","url":"https:\/\/www.atmos.eu\/fr\/\u00e9v\u00e9nement\/infotherma-ostrava-2023\/","name":"Infotherma - Ostrava 2023 - ATMOS","isPartOf":{"@id":"https:\/\/www.atmos.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.atmos.eu\/fr\/\u00e9v\u00e9nement\/infotherma-ostrava-2023\/#primaryimage"},"image":{"@id":"https:\/\/www.atmos.eu\/fr\/\u00e9v\u00e9nement\/infotherma-ostrava-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/www.atmos.eu\/wp-content\/uploads\/2022\/10\/Infotherma-2023-logo-300x156-1.jpg","datePublished":"2022-10-06T13:01:07+00:00","dateModified":"2024-06-11T06:37:40+00:00","breadcrumb":{"@id":"https:\/\/www.atmos.eu\/fr\/\u00e9v\u00e9nement\/infotherma-ostrava-2023\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.atmos.eu\/fr\/\u00e9v\u00e9nement\/infotherma-ostrava-2023\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.atmos.eu\/fr\/\u00e9v\u00e9nement\/infotherma-ostrava-2023\/#primaryimage","url":"https:\/\/www.atmos.eu\/wp-content\/uploads\/2022\/10\/Infotherma-2023-logo-300x156-1.jpg","contentUrl":"https:\/\/www.atmos.eu\/wp-content\/uploads\/2022\/10\/Infotherma-2023-logo-300x156-1.jpg","width":300,"height":156},{"@type":"BreadcrumbList","@id":"https:\/\/www.atmos.eu\/fr\/\u00e9v\u00e9nement\/infotherma-ostrava-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.atmos.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Infotherma &#8211; Ostrava 2023"}]},{"@type":"WebSite","@id":"https:\/\/www.atmos.eu\/fr\/#website","url":"https:\/\/www.atmos.eu\/fr\/","name":"ATMOS","description":"ATMOS","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.atmos.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.atmos.eu\/fr\/wp-json\/wp\/v2\/event\/23417","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.atmos.eu\/fr\/wp-json\/wp\/v2\/event"}],"about":[{"href":"https:\/\/www.atmos.eu\/fr\/wp-json\/wp\/v2\/types\/event"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.atmos.eu\/fr\/wp-json\/wp\/v2\/media\/22624"}],"wp:attachment":[{"href":"https:\/\/www.atmos.eu\/fr\/wp-json\/wp\/v2\/media?parent=23417"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}