{"id":20442,"date":"2022-03-25T09:59:15","date_gmt":"2022-03-25T08:59:15","guid":{"rendered":"https:\/\/www.atmos.eu\/udalost\/for-pasiv-praha-2018\/"},"modified":"2024-06-13T12:41:56","modified_gmt":"2024-06-13T10:41:56","slug":"for-pasiv-praha-2018","status":"publish","type":"event","link":"https:\/\/www.atmos.eu\/es\/Evento\/for-pasiv-praha-2018\/","title":{"rendered":"for pasiv &#8211; praha 2018"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"menu_order":0,"template":"","class_list":["post-20442","event","type-event","status-publish","hentry","event-category-2018-es","tag_event-ceska-republika"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>for pasiv - praha 2018 - ATMOS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.atmos.eu\/es\/Evento\/for-pasiv-praha-2018\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"for pasiv - praha 2018 - ATMOS\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.atmos.eu\/es\/Evento\/for-pasiv-praha-2018\/\" \/>\n<meta property=\"og:site_name\" content=\"ATMOS\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-13T10:41:56+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"for pasiv - praha 2018 - ATMOS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.atmos.eu\/es\/Evento\/for-pasiv-praha-2018\/","og_locale":"es_ES","og_type":"article","og_title":"for pasiv - praha 2018 - ATMOS","og_url":"https:\/\/www.atmos.eu\/es\/Evento\/for-pasiv-praha-2018\/","og_site_name":"ATMOS","article_modified_time":"2024-06-13T10:41:56+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.atmos.eu\/es\/Evento\/for-pasiv-praha-2018\/","url":"https:\/\/www.atmos.eu\/es\/Evento\/for-pasiv-praha-2018\/","name":"for pasiv - praha 2018 - ATMOS","isPartOf":{"@id":"https:\/\/www.atmos.eu\/es\/#website"},"datePublished":"2022-03-25T08:59:15+00:00","dateModified":"2024-06-13T10:41:56+00:00","breadcrumb":{"@id":"https:\/\/www.atmos.eu\/es\/Evento\/for-pasiv-praha-2018\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.atmos.eu\/es\/Evento\/for-pasiv-praha-2018\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.atmos.eu\/es\/Evento\/for-pasiv-praha-2018\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.atmos.eu\/es\/"},{"@type":"ListItem","position":2,"name":"for pasiv &#8211; praha 2018"}]},{"@type":"WebSite","@id":"https:\/\/www.atmos.eu\/es\/#website","url":"https:\/\/www.atmos.eu\/es\/","name":"ATMOS","description":"ATMOS","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.atmos.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.atmos.eu\/es\/wp-json\/wp\/v2\/event\/20442","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.atmos.eu\/es\/wp-json\/wp\/v2\/event"}],"about":[{"href":"https:\/\/www.atmos.eu\/es\/wp-json\/wp\/v2\/types\/event"}],"wp:attachment":[{"href":"https:\/\/www.atmos.eu\/es\/wp-json\/wp\/v2\/media?parent=20442"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}