{"id":19945,"date":"2022-03-25T12:47:21","date_gmt":"2022-03-25T11:47:21","guid":{"rendered":"https:\/\/www.atmos.eu\/udalost\/lesnicky-den-ralsko-2020\/"},"modified":"2024-06-13T14:14:12","modified_gmt":"2024-06-13T12:14:12","slug":"lesnicky-den-ralsko-2020","status":"publish","type":"event","link":"https:\/\/www.atmos.eu\/en\/event\/lesnicky-den-ralsko-2020\/","title":{"rendered":"lesnick\u00fd den &#8211; ralsko 2020"},"content":{"rendered":"<p><span style=\"color: #ff0000;\"><strong><span style=\"font-family: arial, helvetica, sans-serif;\">ZRU\u0160ENO<\/span><\/strong><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>ZRU\u0160ENO<\/p>\n","protected":false},"featured_media":0,"menu_order":0,"template":"","class_list":["post-19945","event","type-event","status-publish","hentry","event-category-2020-en","tag_event-ceska-republika"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>lesnick\u00fd den - ralsko 2020 - ATMOS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.atmos.eu\/en\/event\/lesnicky-den-ralsko-2020\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"lesnick\u00fd den - ralsko 2020 - ATMOS\" \/>\n<meta property=\"og:description\" content=\"ZRU\u0160ENO\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.atmos.eu\/en\/event\/lesnicky-den-ralsko-2020\/\" \/>\n<meta property=\"og:site_name\" content=\"ATMOS\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-13T12:14:12+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"lesnick\u00fd den - ralsko 2020 - ATMOS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.atmos.eu\/en\/event\/lesnicky-den-ralsko-2020\/","og_locale":"en_US","og_type":"article","og_title":"lesnick\u00fd den - ralsko 2020 - ATMOS","og_description":"ZRU\u0160ENO","og_url":"https:\/\/www.atmos.eu\/en\/event\/lesnicky-den-ralsko-2020\/","og_site_name":"ATMOS","article_modified_time":"2024-06-13T12:14:12+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.atmos.eu\/en\/event\/lesnicky-den-ralsko-2020\/","url":"https:\/\/www.atmos.eu\/en\/event\/lesnicky-den-ralsko-2020\/","name":"lesnick\u00fd den - ralsko 2020 - ATMOS","isPartOf":{"@id":"https:\/\/www.atmos.eu\/en\/#website"},"datePublished":"2022-03-25T11:47:21+00:00","dateModified":"2024-06-13T12:14:12+00:00","breadcrumb":{"@id":"https:\/\/www.atmos.eu\/en\/event\/lesnicky-den-ralsko-2020\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.atmos.eu\/en\/event\/lesnicky-den-ralsko-2020\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.atmos.eu\/en\/event\/lesnicky-den-ralsko-2020\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.atmos.eu\/en\/"},{"@type":"ListItem","position":2,"name":"lesnick\u00fd den &#8211; ralsko 2020"}]},{"@type":"WebSite","@id":"https:\/\/www.atmos.eu\/en\/#website","url":"https:\/\/www.atmos.eu\/en\/","name":"ATMOS","description":"ATMOS","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.atmos.eu\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.atmos.eu\/en\/wp-json\/wp\/v2\/event\/19945","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.atmos.eu\/en\/wp-json\/wp\/v2\/event"}],"about":[{"href":"https:\/\/www.atmos.eu\/en\/wp-json\/wp\/v2\/types\/event"}],"wp:attachment":[{"href":"https:\/\/www.atmos.eu\/en\/wp-json\/wp\/v2\/media?parent=19945"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}