{"id":21864,"date":"2022-08-31T12:55:46","date_gmt":"2022-08-31T10:55:46","guid":{"rendered":"https:\/\/www.atmos.eu\/udalost\/for-arch-2022\/"},"modified":"2022-08-31T13:53:40","modified_gmt":"2022-08-31T11:53:40","slug":"for-arch-2022","status":"publish","type":"event","link":"https:\/\/www.atmos.eu\/de\/veranstaltungen\/for-arch-2022\/","title":{"rendered":"FOR ARCH 2022"},"content":{"rendered":"<p style=\"text-align: left;\"><span style=\"font-family: arial, helvetica, sans-serif;\"><strong>FOR ARCH \u2013 Die gr\u00f6\u00dfte Baumesse in der Tschechischen Republik<\/strong><\/span><\/p>\n<p style=\"text-align: left;\"><span style=\"font-family: arial, helvetica, sans-serif;\">FOR ARCH ist eine traditionelle, j\u00e4hrlich stattfindende tschechische Messe. In den 31 Jahren ihres Bestehens hat sie sich zur wichtigsten und meistbesuchten Messe der Bauindustrie in der Tschechischen Republik und zu einem etablierten Treffpunkt von Fachleuten aus dem Bereich Geb\u00e4ude und Konstruktionen entwickelt. Aufgrund ihrer Lage in Prag, einem wichtigen Zentrum der mitteleurop\u00e4ischen Wirtschaft, ist die FOR ARCH eine einzigartige Gelegenheit f\u00fcr in- und ausl\u00e4ndische Aussteller, ihre Dienstleistungen und Produkte im internationalen Wettbewerb zu pr\u00e4sentieren.<\/span><\/p>\n<p style=\"text-align: left;\"><span style=\"font-family: arial, helvetica, sans-serif;\"><strong>MONTAGEZEIT:<\/strong><\/span><\/p>\n<p style=\"text-align: left;\"><span style=\"font-family: arial, helvetica, sans-serif;\">14.\u00a0\u2013 19. 9. 2022,\u00a08.00 &#8211; 22.00 Uhr, MI-MO (vorzeitiger Aufbau am Di. 13.9., 9.00 &#8211; 17.00 Uhr, gegen Geb\u00fchr nach Vereinbarung bestellbar; Information und Bestellung unter mastalirova@abf.cz)<\/span><\/p>\n<p style=\"text-align: left;\"><span style=\"font-family: arial, helvetica, sans-serif;\"><strong>Warum sollten Sie an der Messe FOR ARCH teilnehmen?<\/strong><\/span><\/p>\n<ul>\n<li style=\"text-align: left;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Die gr\u00f6\u00dfte Baumesse in der Tschechischen Republik mit der gr\u00f6\u00dften Besucherzahl und Beteiligung ausl\u00e4ndischer Aussteller<\/span><\/li>\n<li style=\"text-align: left;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Volle Unterst\u00fctzung der Au\u00dfenhandelsabteilung; starke internationale Reichweite der Veranstaltung.<\/span><\/li>\n<li style=\"text-align: left;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Baufachmesse mit der l\u00e4ngsten Tradition in der Tschechischen Republik<\/span><\/li>\n<li style=\"text-align: left;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Teilnahme f\u00fchrender Hersteller und Zulieferer<\/span><\/li>\n<li style=\"text-align: left;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Vertretung von Investoren, Entwicklern, Herstellern, Lieferanten, Handwerkern und anderen aus den Bereichen der Bauwirtschaft<\/span><\/li>\n<li style=\"text-align: left;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Praktische Pr\u00e4sentationen des Baugewerbes und des Handwerks<\/span><\/li>\n<li style=\"text-align: left;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Fachliches Begleitprogramm \u2013 Konferenzen, Seminare, Workshops<\/span><\/li>\n<li style=\"text-align: left;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Umfangreiche Medienkampagne in Tschechien und im Ausland<\/span><\/li>\n<li style=\"text-align: left;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Spezialisierte landesweite Wettbewerbe<\/span><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>33. Internationale Baufachmesse<\/p>\n","protected":false},"featured_media":0,"menu_order":0,"template":"","class_list":["post-21864","event","type-event","status-publish","hentry","event-category-2022-de","tag_event-ceska-republika"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>FOR ARCH 2022 - ATMOS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.atmos.eu\/de\/veranstaltungen\/for-arch-2022\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FOR ARCH 2022 - ATMOS\" \/>\n<meta property=\"og:description\" content=\"33. Internationale Baufachmesse\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.atmos.eu\/de\/veranstaltungen\/for-arch-2022\/\" \/>\n<meta property=\"og:site_name\" content=\"ATMOS\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-31T11:53:40+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2\u00a0Minuten\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FOR ARCH 2022 - ATMOS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.atmos.eu\/de\/veranstaltungen\/for-arch-2022\/","og_locale":"de_DE","og_type":"article","og_title":"FOR ARCH 2022 - ATMOS","og_description":"33. Internationale Baufachmesse","og_url":"https:\/\/www.atmos.eu\/de\/veranstaltungen\/for-arch-2022\/","og_site_name":"ATMOS","article_modified_time":"2022-08-31T11:53:40+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.atmos.eu\/de\/veranstaltungen\/for-arch-2022\/","url":"https:\/\/www.atmos.eu\/de\/veranstaltungen\/for-arch-2022\/","name":"FOR ARCH 2022 - ATMOS","isPartOf":{"@id":"https:\/\/www.atmos.eu\/de\/#website"},"datePublished":"2022-08-31T10:55:46+00:00","dateModified":"2022-08-31T11:53:40+00:00","breadcrumb":{"@id":"https:\/\/www.atmos.eu\/de\/veranstaltungen\/for-arch-2022\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.atmos.eu\/de\/veranstaltungen\/for-arch-2022\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.atmos.eu\/de\/veranstaltungen\/for-arch-2022\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.atmos.eu\/de\/"},{"@type":"ListItem","position":2,"name":"FOR ARCH 2022"}]},{"@type":"WebSite","@id":"https:\/\/www.atmos.eu\/de\/#website","url":"https:\/\/www.atmos.eu\/de\/","name":"ATMOS","description":"ATMOS","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.atmos.eu\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.atmos.eu\/de\/wp-json\/wp\/v2\/event\/21864","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.atmos.eu\/de\/wp-json\/wp\/v2\/event"}],"about":[{"href":"https:\/\/www.atmos.eu\/de\/wp-json\/wp\/v2\/types\/event"}],"wp:attachment":[{"href":"https:\/\/www.atmos.eu\/de\/wp-json\/wp\/v2\/media?parent=21864"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}